{"id":4434,"date":"2023-11-19T09:23:29","date_gmt":"2023-11-19T09:23:29","guid":{"rendered":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/?page_id=4434"},"modified":"2023-12-04T09:32:48","modified_gmt":"2023-12-04T09:32:48","slug":"wordpress","status":"publish","type":"page","link":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wordpress\/","title":{"rendered":"WordPress"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4434\" class=\"elementor elementor-4434\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d43163a e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"d43163a\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-cf07015 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"cf07015\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-41bdc30 elementor-widget elementor-widget-spacer\" data-id=\"41bdc30\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f83bb8b elementor-widget elementor-widget-heading\" data-id=\"f83bb8b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">WORDPRESS<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a5822d elementor-widget elementor-widget-spacer\" data-id=\"7a5822d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6365a80 elementor-drop-cap-yes elementor-drop-cap-view-default elementor-widget elementor-widget-text-editor\" data-id=\"6365a80\" data-element_type=\"widget\" data-settings=\"{&quot;drop_cap&quot;:&quot;yes&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>A sa cr\u00e9ation en 2003, <strong>WordPress<\/strong> \u00e9tait un logiciel permettant le blogging. Mais rapidement, Matt Mullenweg, fondateur de WordPress l\u2019a fait \u00e9voluer vers un r\u00e9el CMS (Content Management System). Aujourd\u2019hui WordPress est devenu un outil incontournable pour la r\u00e9alisation de sites internet. Ainsi, ce sont, en 2022, 43 % des sites qui utilisent WordPress dans le monde, et 20% utilisent WooCommerce !<\/p>\n<p>WordPress est donc d\u00e9sormais un outil qui favorise la relation client \u00e0 distance, et donc la digitalisation de la relation client.\u00a0<\/p>\n<p>Dans le cadre du bloc 2 du BTS NDRC, vous aurez \u00e0 travailler sur la cr\u00e9ation et la personnalisation d\u2019un site WordPress d\u00e9velopp\u00e9 avec le th\u00e8me <strong>ASTRA<\/strong>.<\/p>\n<p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align);\">En effet, le r\u00e9f\u00e9rentiel de BTS NDRC implique l&rsquo;acquisition de <strong>31 comp\u00e9tences<\/strong> pour valider l&rsquo;examen.<\/span><\/p>\n<p>\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2433464 elementor-widget elementor-widget-spacer\" data-id=\"2433464\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9c64e78 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"9c64e78\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-da65694 e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"da65694\" data-element_type=\"widget\" data-settings=\"{&quot;tabs_justify_horizontal&quot;:&quot;stretch&quot;,&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"229004948\" aria-label=\"Onglets. Ouvrez des \u00e9l\u00e9ments avec Entrer ou Espace, fermez-les avec Echape et naviguez \u00e0 l&#039;aide des touches fl\u00e9ch\u00e9es.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-2290049481\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-2290049481\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tTutoriels vid\u00e9o WordPress\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-2290049482\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-2290049482\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tComp\u00e9tences de l'examen\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-2290049483\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-2290049483\" style=\"--n-tabs-title-order: 3;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tLes r\u00f4les dans WordPress\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-2290049481\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2290049481\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-f7791d9 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"f7791d9\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b18001e e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"b18001e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53b4c57 elementor-widget elementor-widget-visual-portfolio\" data-id=\"53b4c57\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"visual-portfolio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\n<div class=\"vp-portfolio vp-uid-09641451 vp-id-4116 \"\n\tdata-vp-layout=\"tiles\" data-vp-content-source=\"post-based\" data-vp-items-style=\"fade\" data-vp-items-click-action=\"popup_gallery\" data-vp-items-gap=\"10\" data-vp-items-gap-vertical=\"\" data-vp-pagination=\"paged\" data-vp-next-page-url=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-json\/wp\/v2\/pages\/4434?cprotect=1&#038;vp_page=2\" data-vp-tiles-type=\"4|1,1|\" >\n\t<div class=\"vp-portfolio__preloader-wrap\">\n\t\t<div class=\"vp-portfolio__preloader\">\n\t\t\t<img decoding=\"async\" loading=\"eager\" src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/plugins\/visual-portfolio\/assets\/images\/logo-dark.svg\" alt=\"Visual Portfolio, Posts &amp; Image Gallery for WordPress\" width=\"20\" height=\"20\" data-skip-lazy>\n\t\t<\/div>\n\t<\/div>\n\t\t<div class=\"vp-portfolio__layout-elements vp-portfolio__layout-elements-top vp-portfolio__layout-elements-align-center\">\n\t\t\t\t<div class=\"vp-portfolio__filter-wrap\">\n\t\t\n<div class=\"vp-filter vp-filter__style-minimal\">\n\t\t\t<div class=\"vp-filter__item vp-filter__item-active\">\n\t\t\t<a href=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-json\/wp\/v2\/pages\/4434?cprotect=1\" data-vp-filter=\"*\">\n\t\t\t\tTous\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<div class=\"vp-filter__item\">\n\t\t\t<a href=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-json\/wp\/v2\/pages\/4434?cprotect=1&#038;vp_filter=portfolio_category%3Aapparence\" data-vp-filter=\"apparence\">\n\t\t\t\tApparence\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<div class=\"vp-filter__item\">\n\t\t\t<a href=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-json\/wp\/v2\/pages\/4434?cprotect=1&#038;vp_filter=portfolio_category%3Aastra\" data-vp-filter=\"astra\">\n\t\t\t\tAstra\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<div class=\"vp-filter__item\">\n\t\t\t<a href=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-json\/wp\/v2\/pages\/4434?cprotect=1&#038;vp_filter=portfolio_category%3Acontenu\" data-vp-filter=\"contenu\">\n\t\t\t\tContenu\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<div class=\"vp-filter__item\">\n\t\t\t<a href=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-json\/wp\/v2\/pages\/4434?cprotect=1&#038;vp_filter=portfolio_category%3Amenu\" data-vp-filter=\"menu\">\n\t\t\t\tMenu\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<div class=\"vp-filter__item\">\n\t\t\t<a href=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-json\/wp\/v2\/pages\/4434?cprotect=1&#038;vp_filter=portfolio_category%3Aseo\" data-vp-filter=\"seo\">\n\t\t\t\tSEO\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<div class=\"vp-filter__item\">\n\t\t\t<a href=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-json\/wp\/v2\/pages\/4434?cprotect=1&#038;vp_filter=portfolio_category%3Autilisateurs\" data-vp-filter=\"utilisateurs\">\n\t\t\t\tUtilisateurs\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vp-portfolio__items-wrap\">\n\t\t\t\n<div class=\"vp-portfolio__items vp-portfolio__items-style-fade vp-portfolio__items-show-overlay-always\">\n\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-1183 portfolio type-portfolio status-publish format-video has-post-thumbnail hentry portfolio_category-seo portfolio_tag-wordpress vp-portfolio__item-uid-ae72c636\" data-vp-filter=\"seo\" style=\"--vp-images__object-position: 40% 51%;\" \t\t>\n\t\t\t\n<template class=\"vp-portfolio__item-popup\" style=\"display: none\" data-vp-popup-video=\"https:\/\/www.youtube.com\/watch?v=dC0Ml_Ad98E\" data-vp-popup-poster=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\">\n\t<\/template>\n\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/portfolio\/yoast-seo\/\"\n\t\taria-label=\"YOAST SEO\" \t>\n\t\n\t\t<noscript><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"400\" data-skip-lazy src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" class=\"wp-image-2260\" alt=\"\" srcset=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png 600w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-300x200.png 300w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-500x333.png 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/noscript><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" class=\"wp-image-2260 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNjAwIiBoZWlnaHQ9IjQwMCIgdmlld0JveD0iMCAwIDYwMCA0MDAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" data-src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" data-srcset=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png 600w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-300x200.png 300w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-500x333.png 500w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<\/a>\t<\/div>\n<\/div>\n\t<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-overlay-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/portfolio\/yoast-seo\/\"\n\t\ttabindex=\"-1\" class=\"vp-portfolio__item-meta\" aria-label=\"YOAST SEO\" \t>\n\t\n\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<span\t\t\t>\n\tSEO<\/span>\t\t<\/div>\n\t\t<\/div>\n\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\tYOAST SEO<\/h2>\n<\/a>\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-1181 portfolio type-portfolio status-publish format-video has-post-thumbnail hentry portfolio_category-menu portfolio_tag-wordpress vp-portfolio__item-uid-407ca71a\" data-vp-filter=\"menu\" \t\t>\n\t\t\t\n<template class=\"vp-portfolio__item-popup\" style=\"display: none\" data-vp-popup-video=\"https:\/\/www.youtube.com\/watch?v=ZzDf50Wx3vw\" data-vp-popup-poster=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\">\n\t<\/template>\n\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/portfolio\/integrer-les-categories-au-menu\/\"\n\t\taria-label=\"Int\u00e9grer les cat\u00e9gories au menu\" \t>\n\t\n\t\t<noscript><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"400\" data-skip-lazy src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" class=\"wp-image-2260\" alt=\"\" srcset=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png 600w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-300x200.png 300w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-500x333.png 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/noscript><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" class=\"wp-image-2260 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNjAwIiBoZWlnaHQ9IjQwMCIgdmlld0JveD0iMCAwIDYwMCA0MDAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" data-src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" data-srcset=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png 600w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-300x200.png 300w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-500x333.png 500w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<\/a>\t<\/div>\n<\/div>\n\t<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-overlay-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/portfolio\/integrer-les-categories-au-menu\/\"\n\t\ttabindex=\"-1\" class=\"vp-portfolio__item-meta\" aria-label=\"Int\u00e9grer les cat\u00e9gories au menu\" \t>\n\t\n\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<span\t\t\t>\n\tMenu<\/span>\t\t<\/div>\n\t\t<\/div>\n\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\tInt\u00e9grer les cat\u00e9gories au menu<\/h2>\n<\/a>\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-1179 portfolio type-portfolio status-publish format-video has-post-thumbnail hentry portfolio_category-apparence portfolio_category-contenu portfolio_category-menu portfolio_tag-wordpress vp-portfolio__item-uid-c93f33e7\" data-vp-filter=\"apparence,contenu,menu\" \t\t>\n\t\t\t\n<template class=\"vp-portfolio__item-popup\" style=\"display: none\" data-vp-popup-video=\"https:\/\/www.youtube.com\/watch?v=Ot9BQbIAFaU\" data-vp-popup-poster=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\">\n\t<\/template>\n\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/portfolio\/les-menus\/\"\n\t\taria-label=\"Les menus\" \t>\n\t\n\t\t<noscript><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"400\" data-skip-lazy src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" class=\"wp-image-2260\" alt=\"\" srcset=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png 600w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-300x200.png 300w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-500x333.png 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/noscript><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" class=\"wp-image-2260 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNjAwIiBoZWlnaHQ9IjQwMCIgdmlld0JveD0iMCAwIDYwMCA0MDAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" data-src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" data-srcset=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png 600w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-300x200.png 300w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-500x333.png 500w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<\/a>\t<\/div>\n<\/div>\n\t<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-overlay-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/portfolio\/les-menus\/\"\n\t\ttabindex=\"-1\" class=\"vp-portfolio__item-meta\" aria-label=\"Les menus\" \t>\n\t\n\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<span\t\t\t>\n\tApparence<\/span>\t\t<\/div>\n\t\t<\/div>\n\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\tLes menus<\/h2>\n<\/a>\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-1177 portfolio type-portfolio status-publish format-video has-post-thumbnail hentry portfolio_category-contenu portfolio_tag-wordpress vp-portfolio__item-uid-2e871ee0\" data-vp-filter=\"contenu\" \t\t>\n\t\t\t\n<template class=\"vp-portfolio__item-popup\" style=\"display: none\" data-vp-popup-video=\"https:\/\/www.youtube.com\/watch?v=3K_Mm8H3ZXA\" data-vp-popup-poster=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\">\n\t<\/template>\n\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/portfolio\/les-commentaires\/\"\n\t\taria-label=\"Les commentaires\" \t>\n\t\n\t\t<noscript><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"400\" data-skip-lazy src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" class=\"wp-image-2260\" alt=\"\" srcset=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png 600w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-300x200.png 300w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-500x333.png 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/noscript><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" class=\"wp-image-2260 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNjAwIiBoZWlnaHQ9IjQwMCIgdmlld0JveD0iMCAwIDYwMCA0MDAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" data-src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" data-srcset=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png 600w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-300x200.png 300w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-500x333.png 500w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<\/a>\t<\/div>\n<\/div>\n\t<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-overlay-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/portfolio\/les-commentaires\/\"\n\t\ttabindex=\"-1\" class=\"vp-portfolio__item-meta\" aria-label=\"Les commentaires\" \t>\n\t\n\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<span\t\t\t>\n\tContenu<\/span>\t\t<\/div>\n\t\t<\/div>\n\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\tLes commentaires<\/h2>\n<\/a>\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-1175 portfolio type-portfolio status-publish format-video has-post-thumbnail hentry portfolio_category-apparence portfolio_category-contenu portfolio_tag-wordpress vp-portfolio__item-uid-c0897fcc\" data-vp-filter=\"apparence,contenu\" \t\t>\n\t\t\t\n<template class=\"vp-portfolio__item-popup\" style=\"display: none\" data-vp-popup-video=\"https:\/\/youtu.be\/8dnNgbc0ZQQ\" data-vp-popup-poster=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\">\n\t<\/template>\n\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/portfolio\/les-categories\/\"\n\t\taria-label=\"Les blocs WordPress\" \t>\n\t\n\t\t<noscript><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"400\" data-skip-lazy src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" class=\"wp-image-2260\" alt=\"\" srcset=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png 600w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-300x200.png 300w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-500x333.png 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/noscript><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" class=\"wp-image-2260 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNjAwIiBoZWlnaHQ9IjQwMCIgdmlld0JveD0iMCAwIDYwMCA0MDAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" data-src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" data-srcset=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png 600w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-300x200.png 300w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-500x333.png 500w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<\/a>\t<\/div>\n<\/div>\n\t<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-overlay-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/portfolio\/les-categories\/\"\n\t\ttabindex=\"-1\" class=\"vp-portfolio__item-meta\" aria-label=\"Les blocs WordPress\" \t>\n\t\n\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<span\t\t\t>\n\tApparence<\/span>\t\t<\/div>\n\t\t<\/div>\n\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\tLes blocs WordPress<\/h2>\n<\/a>\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-1173 portfolio type-portfolio status-publish format-video has-post-thumbnail hentry portfolio_category-contenu portfolio_category-seo portfolio_tag-wordpress vp-portfolio__item-uid-29eadaf9\" data-vp-filter=\"contenu,seo\" \t\t>\n\t\t\t\n<template class=\"vp-portfolio__item-popup\" style=\"display: none\" data-vp-popup-video=\"https:\/\/www.youtube.com\/watch?v=pYdHwBYZk2I\" data-vp-popup-poster=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\">\n\t<\/template>\n\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/portfolio\/categories-et-etiquettes\/\"\n\t\taria-label=\"Cat\u00e9gories et \u00e9tiquettes\" \t>\n\t\n\t\t<noscript><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"400\" data-skip-lazy src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" class=\"wp-image-2260\" alt=\"\" srcset=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png 600w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-300x200.png 300w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-500x333.png 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/noscript><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" class=\"wp-image-2260 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNjAwIiBoZWlnaHQ9IjQwMCIgdmlld0JveD0iMCAwIDYwMCA0MDAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" data-src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" data-srcset=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png 600w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-300x200.png 300w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-500x333.png 500w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<\/a>\t<\/div>\n<\/div>\n\t<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-overlay-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/portfolio\/categories-et-etiquettes\/\"\n\t\ttabindex=\"-1\" class=\"vp-portfolio__item-meta\" aria-label=\"Cat\u00e9gories et \u00e9tiquettes\" \t>\n\t\n\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<span\t\t\t>\n\tContenu<\/span>\t\t<\/div>\n\t\t<\/div>\n\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\tCat\u00e9gories et \u00e9tiquettes<\/h2>\n<\/a>\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-1171 portfolio type-portfolio status-publish format-video has-post-thumbnail hentry portfolio_category-apparence portfolio_category-contenu portfolio_tag-wordpress vp-portfolio__item-uid-c7e4bbd5\" data-vp-filter=\"apparence,contenu\" \t\t>\n\t\t\t\n<template class=\"vp-portfolio__item-popup\" style=\"display: none\" data-vp-popup-video=\"https:\/\/youtu.be\/GwWFvpx-P-g\" data-vp-popup-poster=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\">\n\t<\/template>\n\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/portfolio\/inserer-une-galerie-dimages\/\"\n\t\taria-label=\"Ins\u00e9rer une galerie d&rsquo;images\" \t>\n\t\n\t\t<noscript><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"400\" data-skip-lazy src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" class=\"wp-image-2260\" alt=\"\" srcset=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png 600w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-300x200.png 300w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-500x333.png 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/noscript><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" class=\"wp-image-2260 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNjAwIiBoZWlnaHQ9IjQwMCIgdmlld0JveD0iMCAwIDYwMCA0MDAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" data-src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" data-srcset=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png 600w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-300x200.png 300w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-500x333.png 500w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<\/a>\t<\/div>\n<\/div>\n\t<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-overlay-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/portfolio\/inserer-une-galerie-dimages\/\"\n\t\ttabindex=\"-1\" class=\"vp-portfolio__item-meta\" aria-label=\"Ins\u00e9rer une galerie d&rsquo;images\" \t>\n\t\n\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<span\t\t\t>\n\tApparence<\/span>\t\t<\/div>\n\t\t<\/div>\n\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\tIns\u00e9rer une galerie d&rsquo;images<\/h2>\n<\/a>\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-1168 portfolio type-portfolio status-publish format-video has-post-thumbnail hentry portfolio_category-contenu portfolio_category-seo portfolio_tag-wordpress vp-portfolio__item-uid-a7233230\" data-vp-filter=\"contenu,seo\" \t\t>\n\t\t\t\n<template class=\"vp-portfolio__item-popup\" style=\"display: none\" data-vp-popup-video=\"https:\/\/www.youtube.com\/watch?v=5-mkM6p4xkY\" data-vp-popup-poster=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\">\n\t<\/template>\n\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/portfolio\/liens-internes-et-externes\/\"\n\t\taria-label=\"Liens internes et externes\" \t>\n\t\n\t\t<noscript><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"400\" data-skip-lazy src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" class=\"wp-image-2260\" alt=\"\" srcset=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png 600w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-300x200.png 300w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-500x333.png 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/noscript><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" class=\"wp-image-2260 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNjAwIiBoZWlnaHQ9IjQwMCIgdmlld0JveD0iMCAwIDYwMCA0MDAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" data-src=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png\" data-srcset=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo.png 600w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-300x200.png 300w, https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/07\/wordpressvideo-500x333.png 500w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<\/a>\t<\/div>\n<\/div>\n\t<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-overlay-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/portfolio\/liens-internes-et-externes\/\"\n\t\ttabindex=\"-1\" class=\"vp-portfolio__item-meta\" aria-label=\"Liens internes et externes\" \t>\n\t\n\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<span\t\t\t>\n\tContenu<\/span>\t\t<\/div>\n\t\t<\/div>\n\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\tLiens internes et externes<\/h2>\n<\/a>\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"vp-portfolio__layout-elements vp-portfolio__layout-elements-bottom vp-portfolio__layout-elements-align-center\">\n\t\t\t\t<div class=\"vp-portfolio__pagination-wrap\">\n\t\t\n<div class=\"vp-pagination vp-pagination__style-default\" data-vp-pagination-type=\"paged\"\n>\n\t\t\t<div class=\"vp-pagination__item vp-pagination__item-active\">\n\t\t\t\t\t\t\t<span>1<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vp-pagination__item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-json\/wp\/v2\/pages\/4434?cprotect=1&#038;vp_page=2\">\n\t\t\t\t\t2\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vp-pagination__item vp-pagination__item-next\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-json\/wp\/v2\/pages\/4434?cprotect=1&#038;vp_page=2\">\n\t\t\t\t\t\n<svg class=\"vp-svg-icon\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t<path d=\"M3 10H17\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" fill=\"transparent\" \/>\n\t<path d=\"M11 4L17 10L11 16\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" fill=\"transparent\" \/>\n<\/svg>\n\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-2290049482\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2290049482\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\" elementor-element elementor-element-271df01 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"271df01\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-898f8f6 e-transform e-transform e-transform e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"898f8f6\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-156baa1 e-grid e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"156baa1\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6da7c3e e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"6da7c3e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c0c14c elementor-widget elementor-widget-heading\" data-id=\"1c0c14c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Apparence<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f3ebab elementor-widget elementor-widget-text-editor\" data-id=\"2f3ebab\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul style=\"font-size: 15px;\">\n<li>Cr\u00e9er ou modifier l&rsquo;identit\u00e9 du site (slogan, ic\u00f4ne, logo)<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>Modifier l&rsquo;en-t\u00eate (texte, photo, vid\u00e9o)<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>Activer les r\u00e9seaux sociaux (menu r\u00e9seaux sociaux et widget \u00ab\u00a0ic\u00f4ne des r\u00e9seaux sociaux\u00a0\u00bb)<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>G\u00e9rer les widgets et pied de page et en colonne lat\u00e9rale de blog<\/li>\n<\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-affecd3 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"affecd3\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-938c722 elementor-widget elementor-widget-heading\" data-id=\"938c722\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Image et vid\u00e9o<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-520a90d elementor-widget elementor-widget-text-editor\" data-id=\"520a90d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wp-block-essential-blocks-accordion\">\n<div class=\"eb-parent-wrapper eb-parent-eb-accordion-zugljgz \">\n<div class=\"eb-accordion-container eb-accordion-zugljgz\" data-accordion-type=\"accordion\" data-tab-icon=\"fas fa-angle-right\" data-expanded-icon=\"fas fa-angle-down\">\n<div class=\"eb-accordion-inner\">\n<div class=\"eb-accordion-item-k7nfdt9 eb-accordion-wrapper\" data-clickable=\"false\">\n<div class=\"eb-accordion-content-wrapper\">\n<div class=\"eb-accordion-content\"><!-- wp:list {\"style\":{\"typography\":{\"fontSize\":\"15px\"}}} -->\n<ul style=\"font-size: 15px;\"><!-- wp:list-item -->\n<li>Utiliser une biblioth\u00e8que m\u00e9dia<\/li>\n<li>Ajuster, et positionner un m\u00e9dia<\/li>\n<li>Renseigner les textes alternatifs, le titre, la l\u00e9gende et la description de l&rsquo;image<\/li>\n<li>\u00a0<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7431ef6 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"7431ef6\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23cfe00 elementor-widget elementor-widget-heading\" data-id=\"23cfe00\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Contenu<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d399cb elementor-widget elementor-widget-text-editor\" data-id=\"0d399cb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wp-block-essential-blocks-accordion\">\n<div class=\"eb-parent-wrapper eb-parent-eb-accordion-zugljgz \">\n<div class=\"eb-accordion-container eb-accordion-zugljgz\" data-accordion-type=\"accordion\" data-tab-icon=\"fas fa-angle-right\" data-expanded-icon=\"fas fa-angle-down\">\n<div class=\"eb-accordion-inner\">\n<div class=\"eb-accordion-item-k7nfdt9 eb-accordion-wrapper\" data-clickable=\"false\">\n<div class=\"eb-accordion-content-wrapper\">\n<div class=\"eb-accordion-content\"><!-- wp:list {\"style\":{\"typography\":{\"fontSize\":\"15px\"}}} -->\n<ul style=\"font-size: 15px;\"><!-- wp:list-item -->\n<li>Cr\u00e9er, modifier, publier et supprimer un article, une page et une cat\u00e9gorie<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>R\u00e9diger de mani\u00e8re professionnelle (orthographe, syntaxe, prise en compte du contexte commercial)<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>Utiliser les blocs : titre, paragraphe, bouton, banni\u00e8re, image, galerie, tableau, flux RSS, calendrier, audio, fichier<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>Ajouter un m\u00e9dia (photo, vid\u00e9o, audio)<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>Cr\u00e9er et ins\u00e9rer des liens internes et externes<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>Ins\u00e9rer une carte dynamique via le bloc Map<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>Epingler un article<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>Mod\u00e9rer et r\u00e9pondre \u00e0 un commentaire<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>G\u00e9n\u00e9rer et compl\u00e9ter une page de politique de confidentialit\u00e9<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8a0f9d4 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"8a0f9d4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9c0eee3 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"9c0eee3\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a0fc296 elementor-widget elementor-widget-heading\" data-id=\"a0fc296\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Menu<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32a1ea3 elementor-widget elementor-widget-text-editor\" data-id=\"32a1ea3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"eb-accordion-content-wrapper\">\n<div class=\"eb-accordion-content\"><!-- wp:list {\"style\":{\"typography\":{\"fontSize\":\"15px\"}}} -->\n<ul style=\"font-size: 15px;\"><!-- wp:list-item -->\n<li>Cr\u00e9er ou modifier les menus et sous-menus<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>Ajouter \u00e0 un menu (cat\u00e9gorie, page, lien personnalis\u00e9)<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>Param\u00e9trer le menu des r\u00e9seaux sociaux<\/li>\n<\/ul>\n<\/div>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-410d5b6 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"410d5b6\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b50be5 elementor-widget elementor-widget-heading\" data-id=\"5b50be5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Navigation<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38c8544 elementor-widget elementor-widget-text-editor\" data-id=\"38c8544\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul>\n<li class=\"eb-accordion-content-wrapper\">Utiliser les onglets backoffice et frontoffice<\/li>\n<li class=\"eb-accordion-content-wrapper\">Param\u00e9trer la page d&rsquo;accueil (page statique ou affichage des derniers articles)<\/li>\n<li class=\"eb-accordion-content-wrapper\">Modifier les r\u00e9glages de lecture et de commentaires<\/li>\n<\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-59362e7 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"59362e7\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3b5b30b e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"3b5b30b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7815b83 elementor-widget elementor-widget-heading\" data-id=\"7815b83\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">R\u00e9f\u00e9rencement naturel (SEO)<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91487da elementor-widget elementor-widget-text-editor\" data-id=\"91487da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul style=\"font-size: 15px;\">\n<li>Structurer le texte (titre, sous-titres)<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>Utiliser des mots cl\u00e9s<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>Utiliser des liens internes et externes<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>Renseigner les \u00e9tiquettes, balises et descriptions<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>Activer et utiliser l&rsquo;extension Yoast SEO (requ\u00eate cible, meta\u00a0description<\/li>\n<\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-58c4bb6 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"58c4bb6\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ed32ae4 elementor-widget elementor-widget-heading\" data-id=\"ed32ae4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Utilisateurs<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f36aa68 elementor-widget elementor-widget-text-editor\" data-id=\"f36aa68\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<!-- wp:block {\"ref\":1619} \/--><!-- wp:essential-blocks\/advanced-heading {\"blockId\":\"eb-advance-heading-qmc7mj9\",\"blockMeta\":{\"desktop\":\" .eb-advance-heading-wrapper.eb-advance-heading-qmc7mj9{ position: relative; text-align: center; transition:background 0.5s, border 0.5s, border-radius 0.5s, box-shadow 0.5s ; }  .eb-advance-heading-wrapper.eb-advance-heading-qmc7mj9:before{ transition:background 0.5s, opacity 0.5s, filter 0.5s; }  .eb-advance-heading-wrapper.eb-advance-heading-qmc7mj9 .eb-ah-title { text-align: center; color: var(\\u002d\\u002dast-global-color-2); margin-top: 0px; margin-right: 0px; margin-left: 0px; margin-bottom: 15px; } .eb-advance-heading-wrapper.eb-advance-heading-qmc7mj9:hover .eb-ah-title { color: undefined; } .eb-advance-heading-wrapper.eb-advance-heading-qmc7mj9 .eb-ah-subtitle { text-align: center; color: #555555; margin-top: 0px; margin-right: 0px; margin-left: 0px; margin-bottom: 20px; } .eb-advance-heading-wrapper.eb-advance-heading-qmc7mj9:hover .eb-ah-subtitle { color: undefined; } .eb-advance-heading-wrapper.eb-advance-heading-qmc7mj9 .eb-ah-separator { color: #555555; margin-top: 0px; margin-right: 0px; margin-left: 0px; margin-bottom: 0px; } .eb-advance-heading-wrapper.eb-advance-heading-qmc7mj9 .eb-ah-separator.line { border-style: none none solid; border-color: var(\\u002d\\u002dast-global-color-2); border-width:4px; width:100px; margin-left: auto; margin-right: auto } .eb-advance-heading-wrapper.eb-advance-heading-qmc7mj9:hover .eb-ah-separator.line { border-color: undefined; } .eb-advance-heading-wrapper.eb-advance-heading-qmc7mj9 .eb-ah-separator.icon { text-align: center; color: var(\\u002d\\u002dast-global-color-2); font-size:30px; } .eb-advance-heading-wrapper.eb-advance-heading-qmc7mj9:hover .eb-ah-separator.icon { color: undefined; } \",\"tab\":\"          \",\"mobile\":\"          \"},\"titleText\":\"Les comp\u00e9tences WordPress du BTS NDRC\",\"titleColor\":\"var(\\u002d\\u002dast-global-color-2)\",\"separatorColor\":\"var(\\u002d\\u002dast-global-color-2)\",\"align\":\"center\",\"displaySeperator\":true,\"commonStyles\":{\"desktop\":\" .wp-admin .eb-parent-eb-advance-heading-qmc7mj9 { display: block; opacity: 1; } .eb-parent-eb-advance-heading-qmc7mj9 { display: block; } \",\"tab\":\" .editor-styles-wrapper.wp-embed-responsive .eb-parent-eb-advance-heading-qmc7mj9 { display: block; opacity: 1; } .eb-parent-eb-advance-heading-qmc7mj9 { display: block; } \",\"mobile\":\" .editor-styles-wrapper.wp-embed-responsive .eb-parent-eb-advance-heading-qmc7mj9 { display: block; opacity: 1; } .eb-parent-eb-advance-heading-qmc7mj9 { display: block; } \"}} -->\n<div class=\"wp-block-essential-blocks-accordion\">\n<div class=\"eb-parent-wrapper eb-parent-eb-accordion-zugljgz \">\n<div class=\"eb-accordion-container eb-accordion-zugljgz\" data-accordion-type=\"accordion\" data-tab-icon=\"fas fa-angle-right\" data-expanded-icon=\"fas fa-angle-down\">\n<div class=\"eb-accordion-inner\">\n<div class=\"eb-accordion-item-vpy7v4p eb-accordion-wrapper\" data-clickable=\"false\">\n<div class=\"eb-accordion-content-wrapper\">\n<div class=\"eb-accordion-content\"><!-- wp:list {\"style\":{\"typography\":{\"fontSize\":\"15px\"}}} -->\n<ul style=\"font-size: 15px;\"><!-- wp:list-item -->\n<li>Cr\u00e9er, modifier ou supprimer un compte<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>Attribuer un r\u00f4le<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>Changer l&rsquo;auteur d&rsquo;un article ou d&rsquo;une page<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list --><\/div>\n<\/div>\n<\/div>\n<!-- \/wp:essential-blocks\/accordion-item --><\/div>\n<\/div>\n<\/div>\n<\/div>\n<!-- \/wp:essential-blocks\/accordion -->\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-2290049483\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2290049483\" data-tab-index=\"3\" style=\"--n-tabs-title-order: 3;\" class=\" elementor-element elementor-element-803dd8a e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"803dd8a\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9c31164 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"9c31164\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-018e25b elementor-widget elementor-widget-text-editor\" data-id=\"018e25b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>WordPress offre la possibilit\u00e9 de d\u00e9finir diff\u00e9rents r\u00f4les pour les utilisateurs. En effet, plusieurs utilisateurs participent souvent \u00e0 la cr\u00e9ation et \u00e0 la maintenance du site. Dans cet article, nous allons voir quels sont les r\u00f4les disponibles dans WordPress, quelles sont leurs caract\u00e9ristiques et comment les attribuer aux utilisateurs.<\/p>\n<p>Les r\u00f4les dans WordPress sont un moyen efficace de g\u00e9rer les droits et les responsabilit\u00e9s des utilisateurs. Il est important de choisir le r\u00f4le appropri\u00e9 pour chaque utilisateur en fonction de ses besoins et de ses comp\u00e9tences. Cela permet de garantir la s\u00e9curit\u00e9, la qualit\u00e9 et la coh\u00e9rence du contenu du site.<\/p>\n<p>WordPress propose six r\u00f4les par d\u00e9faut pour les utilisateurs :<\/p>\n<ul>\n<li>administrateur,<\/li>\n<li>\u00e9diteur,<\/li>\n<li>auteur,<\/li>\n<li>contributeur,<\/li>\n<li>abonn\u00e9<\/li>\n<li>super-administrateur (ce dernier n\u2019appara\u00eet que dans les sites \u00ab\u00a0multisites\u2019).<\/li>\n<\/ul>\n<p>Il est possible de modifier ou de cr\u00e9er des r\u00f4les personnalis\u00e9s avec des extensions sp\u00e9cifiques.<\/p>\n<p>Pour attribuer un r\u00f4le \u00e0 un utilisateur visionnez la vid\u00e9os que vous trouverez dans les\u00a0<a href=\"https:\/\/www.ndrcsupalta.fr\/tutoriels-wordpress\/\">tutoriels vid\u00e9o<\/a>\u00a0d\u00e9di\u00e9s \u00e0 WordPress.<\/p>\n<p>Chaque r\u00f4le dispose de certaines capacit\u00e9s qui lui permettent d\u2019effectuer des actions sur le site. Vous trouverez dans le tableau ci-dessous les permissions attach\u00e9es \u00e0 chaque r\u00f4le.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ad9494 elementor-widget elementor-widget-text-editor\" data-id=\"3ad9494\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><!-- wp:block {\"ref\":1619,\"UAGDay\":[]} \/--><!-- wp:uagb\/separator {\"block_id\":\"42b4ceb0\",\"separatorStyle\":\"none\",\"UAGDay\":[]} --><\/p>\n<div class=\"wp-block-group\"><!-- \/wp:paragraph --><!-- wp:table {\"className\":\"is-style-stripes\"} -->\n<figure class=\"wp-block-table is-style-stripes\">\n<table>\n<thead>\n<tr>\n<th>\u00a0<\/th>\n<th class=\"has-text-align-center\" data-align=\"center\">Abonn\u00e9<\/th>\n<th class=\"has-text-align-center\" data-align=\"center\">Contributeur<\/th>\n<th class=\"has-text-align-center\" data-align=\"center\">Auteur<\/th>\n<th class=\"has-text-align-center\" data-align=\"center\">Editeur<\/th>\n<th class=\"has-text-align-center\" data-align=\"center\">Administrateur<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>R\u00e9daction article<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">NON<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<\/tr>\n<tr>\n<td>R\u00e9daction page<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">NON<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">NON<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">NON<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<\/tr>\n<tr>\n<td>Insertion d&rsquo;image \u00e0 partir d&rsquo;une URL<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<\/tr>\n<tr>\n<td>Acc\u00e8s m\u00e9diath\u00e8que<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">NON<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<\/tr>\n<tr>\n<td>Cr\u00e9ation de cat\u00e9gories<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">NON<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">NON<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<\/tr>\n<tr>\n<td>Cr\u00e9ation d&rsquo;\u00e9tiquette<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">NON<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<\/tr>\n<tr>\n<td>Publier<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">NON<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<\/tr>\n<tr>\n<td>Modification de contenu<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">NON<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">NON<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<\/tr>\n<tr>\n<td>Suppression<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">Publications <br \/>personnelles<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">Toutes<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">Toutes<\/td>\n<\/tr>\n<tr>\n<td>Mod\u00e9ration commentaires<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">NON<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">NON<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">NON<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<\/tr>\n<tr>\n<td>Consultation profil<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<\/tr>\n<tr>\n<td>Yoast SEO<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<\/tr>\n<tr>\n<td>Gestion des options du site<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">NON<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">NON<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">NON<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">NON<\/td>\n<td class=\"has-text-align-center\" data-align=\"center\">OUI<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/figure>\n<!-- \/wp:table --><\/div>\n<p><!-- \/wp:group --><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>WORDPRESS A sa cr\u00e9ation en 2003, WordPress \u00e9tait un logiciel permettant le blogging. Mais rapidement, Matt Mullenweg, fondateur de WordPress l\u2019a fait \u00e9voluer vers un r\u00e9el CMS (Content Management System). Aujourd\u2019hui WordPress est devenu un outil incontournable pour la r\u00e9alisation de sites internet. Ainsi, ce sont, en 2022, 43 % des sites qui utilisent WordPress dans le monde, et 20% utilisent WooCommerce ! WordPress est donc d\u00e9sormais un outil qui favorise la relation client \u00e0 distance, et donc la digitalisation de la relation client.\u00a0 Dans le cadre du bloc 2 du BTS NDRC, vous aurez \u00e0 travailler sur la cr\u00e9ation et la personnalisation d\u2019un site WordPress d\u00e9velopp\u00e9 avec le th\u00e8me ASTRA. En effet, le r\u00e9f\u00e9rentiel de BTS NDRC implique l&rsquo;acquisition de 31 comp\u00e9tences pour valider l&rsquo;examen. \u00a0 Tutoriels vid\u00e9o WordPress Comp\u00e9tences de l&rsquo;examen Les r\u00f4les dans WordPress Tous Apparence Astra Contenu Menu SEO Utilisateurs SEO YOAST SEO Menu Int\u00e9grer les cat\u00e9gories au menu Apparence Les menus Contenu Les commentaires Apparence Les blocs WordPress Contenu Cat\u00e9gories et \u00e9tiquettes Apparence Ins\u00e9rer une galerie d&#8217;images Contenu Liens internes et externes 1 2 Apparence Cr\u00e9er ou modifier l&#8217;identit\u00e9 du site (slogan, ic\u00f4ne, logo) Modifier l&#8217;en-t\u00eate (texte, photo, vid\u00e9o) Activer les r\u00e9seaux sociaux (menu r\u00e9seaux sociaux et widget &#8220;ic\u00f4ne des r\u00e9seaux sociaux&#8221;) Utiliser une biblioth\u00e8que m\u00e9dia Ajuster, et positionner un m\u00e9dia Renseigner les textes alternatifs, le titre, la l\u00e9gende et la description de l&rsquo;image \u00a0 Contenu Cr\u00e9er, modifier, publier et supprimer un article, une page et une cat\u00e9gorie R\u00e9diger de mani\u00e8re professionnelle (orthographe, syntaxe, prise en compte du contexte commercial) Utiliser les blocs : titre, paragraphe, bouton, banni\u00e8re, image, galerie, tableau, flux RSS, calendrier, audio, fichier Ajouter un m\u00e9dia (photo, vid\u00e9o, audio) Cr\u00e9er et ins\u00e9rer des liens internes et externes Ins\u00e9rer une carte dynamique via le bloc Map Epingler un article Mod\u00e9rer et r\u00e9pondre \u00e0 un commentaire G\u00e9n\u00e9rer et compl\u00e9ter une page de politique de confidentialit\u00e9 Menu Cr\u00e9er ou modifier les menus et sous-menus Ajouter \u00e0 un menu (cat\u00e9gorie, page, lien personnalis\u00e9) Param\u00e9trer le menu des r\u00e9seaux sociaux Navigation Utiliser les onglets backoffice et frontoffice Param\u00e9trer la page d&rsquo;accueil (page statique ou affichage des derniers articles) Modifier les r\u00e9glages de lecture et de commentaires R\u00e9f\u00e9rencement naturel (SEO) Structurer le texte (titre, sous-titres) Utiliser des mots cl\u00e9s Utiliser des liens internes et externes Renseigner les \u00e9tiquettes, balises et descriptions Activer et utiliser l&rsquo;extension Yoast SEO (requ\u00eate cible, meta\u00a0description Utilisateurs Cr\u00e9er, modifier ou supprimer un compte Attribuer un r\u00f4le Changer l&rsquo;auteur d&rsquo;un article ou d&rsquo;une page WordPress offre la possibilit\u00e9 de d\u00e9finir diff\u00e9rents r\u00f4les pour les utilisateurs. En effet, plusieurs utilisateurs participent souvent \u00e0 la cr\u00e9ation et \u00e0 la maintenance du site. Dans cet article, nous allons voir quels sont les r\u00f4les disponibles dans WordPress, quelles sont leurs caract\u00e9ristiques et comment les attribuer aux utilisateurs. Les r\u00f4les dans WordPress sont un moyen efficace de g\u00e9rer les droits et les responsabilit\u00e9s des utilisateurs. Il est important de choisir le r\u00f4le appropri\u00e9 pour chaque utilisateur en fonction de ses besoins et de ses comp\u00e9tences. Cela permet de garantir la s\u00e9curit\u00e9, la qualit\u00e9 et la coh\u00e9rence du contenu du site. WordPress propose six r\u00f4les par d\u00e9faut pour les utilisateurs : administrateur, \u00e9diteur, auteur, contributeur, abonn\u00e9 super-administrateur (ce dernier n\u2019appara\u00eet que dans les sites \u00ab\u00a0multisites\u2019). Il est possible de modifier ou de cr\u00e9er des r\u00f4les personnalis\u00e9s avec des extensions sp\u00e9cifiques. Pour attribuer un r\u00f4le \u00e0 un utilisateur visionnez la vid\u00e9os que vous trouverez dans les\u00a0tutoriels vid\u00e9o\u00a0d\u00e9di\u00e9s \u00e0 WordPress. Chaque r\u00f4le dispose de certaines capacit\u00e9s qui lui permettent d\u2019effectuer des actions sur le site. Vous trouverez dans le tableau ci-dessous les permissions attach\u00e9es \u00e0 chaque r\u00f4le. \u00a0 Abonn\u00e9 Contributeur Auteur Editeur Administrateur R\u00e9daction article NON OUI OUI OUI OUI R\u00e9daction page NON NON NON OUI OUI Insertion d&rsquo;image \u00e0 partir d&rsquo;une URL OUI OUI OUI OUI OUI Acc\u00e8s m\u00e9diath\u00e8que NON OUI OUI OUI OUI Cr\u00e9ation de cat\u00e9gories NON NON OUI OUI OUI Cr\u00e9ation d&rsquo;\u00e9tiquette NON OUI OUI OUI OUI Publier NON OUI OUI OUI OUI Modification de contenu NON NON OUI OUI OUI Suppression OUI OUI Publications personnelles Toutes Toutes Mod\u00e9ration commentaires NON NON NON OUI OUI Consultation profil OUI OUI OUI OUI OUI Yoast SEO OUI OUI OUI OUI OUI Gestion des options du site NON NON NON NON OUI Utiliser une biblioth\u00e8que m\u00e9dia Ajuster, et positionner un m\u00e9dia Renseigner les textes alternatifs, le titre, la l\u00e9gende et la description de l&rsquo;image \u00a0 Contenu Cr\u00e9er, modifier, publier et supprimer un article, une page et une cat\u00e9gorie R\u00e9diger de mani\u00e8re professionnelle (orthographe, syntaxe, prise en compte du contexte commercial) Utiliser les blocs : titre, paragraphe, bouton, banni\u00e8re, image, galerie, tableau, flux RSS, calendrier, audio, fichier Ajouter un m\u00e9dia (photo, vid\u00e9o, audio) Cr\u00e9er et ins\u00e9rer des liens internes et externes Ins\u00e9rer une carte dynamique via le bloc Map Epingler un article Mod\u00e9rer et r\u00e9pondre \u00e0 un commentaire G\u00e9n\u00e9rer et compl\u00e9ter une page de politique de confidentialit\u00e9 Menu Cr\u00e9er ou modifier les menus et sous-menus Ajouter \u00e0 un menu (cat\u00e9gorie, page, lien personnalis\u00e9) Param\u00e9trer le menu des r\u00e9seaux sociaux Navigation Utiliser les onglets backoffice et frontoffice Param\u00e9trer la page d&rsquo;accueil (page statique ou affichage des derniers articles) Modifier les r\u00e9glages de lecture et de commentaires R\u00e9f\u00e9rencement naturel (SEO) Structurer le texte (titre, sous-titres) Utiliser des mots cl\u00e9s Utiliser des liens internes et externes Renseigner les \u00e9tiquettes, balises et descriptions Activer et utiliser l&rsquo;extension Yoast SEO (requ\u00eate cible, meta\u00a0description Utilisateurs Cr\u00e9er, modifier ou supprimer un compte Attribuer un r\u00f4le Changer l&rsquo;auteur d&rsquo;un article ou d&rsquo;une page WordPress offre la possibilit\u00e9 de d\u00e9finir diff\u00e9rents r\u00f4les pour les utilisateurs. En effet, plusieurs utilisateurs participent souvent \u00e0 la cr\u00e9ation et \u00e0 la maintenance du site. Dans cet article, nous allons voir quels sont les r\u00f4les disponibles dans WordPress, quelles sont leurs caract\u00e9ristiques et comment les attribuer aux utilisateurs. Les r\u00f4les dans WordPress sont un moyen efficace de g\u00e9rer les droits et les responsabilit\u00e9s des utilisateurs. Il est important de choisir le r\u00f4le appropri\u00e9 pour chaque utilisateur en fonction de ses besoins et de ses comp\u00e9tences. Cela permet de garantir la s\u00e9curit\u00e9, la qualit\u00e9 et la coh\u00e9rence du<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_eb_attr":"","inline_featured_image":false,"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"class_list":["post-4434","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wordpress - Relation Client \u00e0 Distance et Digitalisation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wordpress\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wordpress - Relation Client \u00e0 Distance et Digitalisation\" \/>\n<meta property=\"og:description\" content=\"WORDPRESS A sa cr\u00e9ation en 2003, WordPress \u00e9tait un logiciel permettant le blogging. Mais rapidement, Matt Mullenweg, fondateur de WordPress l\u2019a fait \u00e9voluer vers un r\u00e9el CMS (Content Management System). Aujourd\u2019hui WordPress est devenu un outil incontournable pour la r\u00e9alisation de sites internet. Ainsi, ce sont, en 2022, 43 % des sites qui utilisent WordPress dans le monde, et 20% utilisent WooCommerce ! WordPress est donc d\u00e9sormais un outil qui favorise la relation client \u00e0 distance, et donc la digitalisation de la relation client.\u00a0 Dans le cadre du bloc 2 du BTS NDRC, vous aurez \u00e0 travailler sur la cr\u00e9ation et la personnalisation d\u2019un site WordPress d\u00e9velopp\u00e9 avec le th\u00e8me ASTRA. En effet, le r\u00e9f\u00e9rentiel de BTS NDRC implique l&rsquo;acquisition de 31 comp\u00e9tences pour valider l&rsquo;examen. \u00a0 Tutoriels vid\u00e9o WordPress Comp\u00e9tences de l&rsquo;examen Les r\u00f4les dans WordPress Tous Apparence Astra Contenu Menu SEO Utilisateurs SEO YOAST SEO Menu Int\u00e9grer les cat\u00e9gories au menu Apparence Les menus Contenu Les commentaires Apparence Les blocs WordPress Contenu Cat\u00e9gories et \u00e9tiquettes Apparence Ins\u00e9rer une galerie d&#8217;images Contenu Liens internes et externes 1 2 Apparence Cr\u00e9er ou modifier l&#8217;identit\u00e9 du site (slogan, ic\u00f4ne, logo) Modifier l&#8217;en-t\u00eate (texte, photo, vid\u00e9o) Activer les r\u00e9seaux sociaux (menu r\u00e9seaux sociaux et widget &#8220;ic\u00f4ne des r\u00e9seaux sociaux&#8221;) Utiliser une biblioth\u00e8que m\u00e9dia Ajuster, et positionner un m\u00e9dia Renseigner les textes alternatifs, le titre, la l\u00e9gende et la description de l&rsquo;image \u00a0 Contenu Cr\u00e9er, modifier, publier et supprimer un article, une page et une cat\u00e9gorie R\u00e9diger de mani\u00e8re professionnelle (orthographe, syntaxe, prise en compte du contexte commercial) Utiliser les blocs : titre, paragraphe, bouton, banni\u00e8re, image, galerie, tableau, flux RSS, calendrier, audio, fichier Ajouter un m\u00e9dia (photo, vid\u00e9o, audio) Cr\u00e9er et ins\u00e9rer des liens internes et externes Ins\u00e9rer une carte dynamique via le bloc Map Epingler un article Mod\u00e9rer et r\u00e9pondre \u00e0 un commentaire G\u00e9n\u00e9rer et compl\u00e9ter une page de politique de confidentialit\u00e9 Menu Cr\u00e9er ou modifier les menus et sous-menus Ajouter \u00e0 un menu (cat\u00e9gorie, page, lien personnalis\u00e9) Param\u00e9trer le menu des r\u00e9seaux sociaux Navigation Utiliser les onglets backoffice et frontoffice Param\u00e9trer la page d&rsquo;accueil (page statique ou affichage des derniers articles) Modifier les r\u00e9glages de lecture et de commentaires R\u00e9f\u00e9rencement naturel (SEO) Structurer le texte (titre, sous-titres) Utiliser des mots cl\u00e9s Utiliser des liens internes et externes Renseigner les \u00e9tiquettes, balises et descriptions Activer et utiliser l&rsquo;extension Yoast SEO (requ\u00eate cible, meta\u00a0description Utilisateurs Cr\u00e9er, modifier ou supprimer un compte Attribuer un r\u00f4le Changer l&rsquo;auteur d&rsquo;un article ou d&rsquo;une page WordPress offre la possibilit\u00e9 de d\u00e9finir diff\u00e9rents r\u00f4les pour les utilisateurs. En effet, plusieurs utilisateurs participent souvent \u00e0 la cr\u00e9ation et \u00e0 la maintenance du site. Dans cet article, nous allons voir quels sont les r\u00f4les disponibles dans WordPress, quelles sont leurs caract\u00e9ristiques et comment les attribuer aux utilisateurs. Les r\u00f4les dans WordPress sont un moyen efficace de g\u00e9rer les droits et les responsabilit\u00e9s des utilisateurs. Il est important de choisir le r\u00f4le appropri\u00e9 pour chaque utilisateur en fonction de ses besoins et de ses comp\u00e9tences. Cela permet de garantir la s\u00e9curit\u00e9, la qualit\u00e9 et la coh\u00e9rence du contenu du site. WordPress propose six r\u00f4les par d\u00e9faut pour les utilisateurs : administrateur, \u00e9diteur, auteur, contributeur, abonn\u00e9 super-administrateur (ce dernier n\u2019appara\u00eet que dans les sites \u00ab\u00a0multisites\u2019). Il est possible de modifier ou de cr\u00e9er des r\u00f4les personnalis\u00e9s avec des extensions sp\u00e9cifiques. Pour attribuer un r\u00f4le \u00e0 un utilisateur visionnez la vid\u00e9os que vous trouverez dans les\u00a0tutoriels vid\u00e9o\u00a0d\u00e9di\u00e9s \u00e0 WordPress. Chaque r\u00f4le dispose de certaines capacit\u00e9s qui lui permettent d\u2019effectuer des actions sur le site. Vous trouverez dans le tableau ci-dessous les permissions attach\u00e9es \u00e0 chaque r\u00f4le. \u00a0 Abonn\u00e9 Contributeur Auteur Editeur Administrateur R\u00e9daction article NON OUI OUI OUI OUI R\u00e9daction page NON NON NON OUI OUI Insertion d&rsquo;image \u00e0 partir d&rsquo;une URL OUI OUI OUI OUI OUI Acc\u00e8s m\u00e9diath\u00e8que NON OUI OUI OUI OUI Cr\u00e9ation de cat\u00e9gories NON NON OUI OUI OUI Cr\u00e9ation d&rsquo;\u00e9tiquette NON OUI OUI OUI OUI Publier NON OUI OUI OUI OUI Modification de contenu NON NON OUI OUI OUI Suppression OUI OUI Publications personnelles Toutes Toutes Mod\u00e9ration commentaires NON NON NON OUI OUI Consultation profil OUI OUI OUI OUI OUI Yoast SEO OUI OUI OUI OUI OUI Gestion des options du site NON NON NON NON OUI Utiliser une biblioth\u00e8que m\u00e9dia Ajuster, et positionner un m\u00e9dia Renseigner les textes alternatifs, le titre, la l\u00e9gende et la description de l&rsquo;image \u00a0 Contenu Cr\u00e9er, modifier, publier et supprimer un article, une page et une cat\u00e9gorie R\u00e9diger de mani\u00e8re professionnelle (orthographe, syntaxe, prise en compte du contexte commercial) Utiliser les blocs : titre, paragraphe, bouton, banni\u00e8re, image, galerie, tableau, flux RSS, calendrier, audio, fichier Ajouter un m\u00e9dia (photo, vid\u00e9o, audio) Cr\u00e9er et ins\u00e9rer des liens internes et externes Ins\u00e9rer une carte dynamique via le bloc Map Epingler un article Mod\u00e9rer et r\u00e9pondre \u00e0 un commentaire G\u00e9n\u00e9rer et compl\u00e9ter une page de politique de confidentialit\u00e9 Menu Cr\u00e9er ou modifier les menus et sous-menus Ajouter \u00e0 un menu (cat\u00e9gorie, page, lien personnalis\u00e9) Param\u00e9trer le menu des r\u00e9seaux sociaux Navigation Utiliser les onglets backoffice et frontoffice Param\u00e9trer la page d&rsquo;accueil (page statique ou affichage des derniers articles) Modifier les r\u00e9glages de lecture et de commentaires R\u00e9f\u00e9rencement naturel (SEO) Structurer le texte (titre, sous-titres) Utiliser des mots cl\u00e9s Utiliser des liens internes et externes Renseigner les \u00e9tiquettes, balises et descriptions Activer et utiliser l&rsquo;extension Yoast SEO (requ\u00eate cible, meta\u00a0description Utilisateurs Cr\u00e9er, modifier ou supprimer un compte Attribuer un r\u00f4le Changer l&rsquo;auteur d&rsquo;un article ou d&rsquo;une page WordPress offre la possibilit\u00e9 de d\u00e9finir diff\u00e9rents r\u00f4les pour les utilisateurs. En effet, plusieurs utilisateurs participent souvent \u00e0 la cr\u00e9ation et \u00e0 la maintenance du site. Dans cet article, nous allons voir quels sont les r\u00f4les disponibles dans WordPress, quelles sont leurs caract\u00e9ristiques et comment les attribuer aux utilisateurs. Les r\u00f4les dans WordPress sont un moyen efficace de g\u00e9rer les droits et les responsabilit\u00e9s des utilisateurs. Il est important de choisir le r\u00f4le appropri\u00e9 pour chaque utilisateur en fonction de ses besoins et de ses comp\u00e9tences. Cela permet de garantir la s\u00e9curit\u00e9, la qualit\u00e9 et la coh\u00e9rence du\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wordpress\/\" \/>\n<meta property=\"og:site_name\" content=\"Relation Client \u00e0 Distance et Digitalisation\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-04T09:32:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/plugins\/visual-portfolio\/assets\/images\/logo-dark.svg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.anouk.louisst.o2switch.site\\\/rcdd\\\/wordpress\\\/\",\"url\":\"https:\\\/\\\/www.anouk.louisst.o2switch.site\\\/rcdd\\\/wordpress\\\/\",\"name\":\"Wordpress - Relation Client \u00e0 Distance et Digitalisation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.anouk.louisst.o2switch.site\\\/rcdd\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.anouk.louisst.o2switch.site\\\/rcdd\\\/wordpress\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.anouk.louisst.o2switch.site\\\/rcdd\\\/wordpress\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.anouk.louisst.o2switch.site\\\/rcdd\\\/wp-content\\\/plugins\\\/visual-portfolio\\\/assets\\\/images\\\/logo-dark.svg\",\"datePublished\":\"2023-11-19T09:23:29+00:00\",\"dateModified\":\"2023-12-04T09:32:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.anouk.louisst.o2switch.site\\\/rcdd\\\/wordpress\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.anouk.louisst.o2switch.site\\\/rcdd\\\/wordpress\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.anouk.louisst.o2switch.site\\\/rcdd\\\/wordpress\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.anouk.louisst.o2switch.site\\\/rcdd\\\/wp-content\\\/plugins\\\/visual-portfolio\\\/assets\\\/images\\\/logo-dark.svg\",\"contentUrl\":\"https:\\\/\\\/www.anouk.louisst.o2switch.site\\\/rcdd\\\/wp-content\\\/plugins\\\/visual-portfolio\\\/assets\\\/images\\\/logo-dark.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.anouk.louisst.o2switch.site\\\/rcdd\\\/wordpress\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.anouk.louisst.o2switch.site\\\/rcdd\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WordPress\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.anouk.louisst.o2switch.site\\\/rcdd\\\/#website\",\"url\":\"https:\\\/\\\/www.anouk.louisst.o2switch.site\\\/rcdd\\\/\",\"name\":\"Relation Client \u00e0 Distance et Digitalisation\",\"description\":\"BTS NDRC\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.anouk.louisst.o2switch.site\\\/rcdd\\\/#\\\/schema\\\/person\\\/f30535236471ed9f12122e0e70841b24\"},\"alternateName\":\"RCDD\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.anouk.louisst.o2switch.site\\\/rcdd\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.anouk.louisst.o2switch.site\\\/rcdd\\\/#\\\/schema\\\/person\\\/f30535236471ed9f12122e0e70841b24\",\"name\":\"adoligez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.anouk.louisst.o2switch.site\\\/rcdd\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/RCDD-9.png\",\"url\":\"https:\\\/\\\/www.anouk.louisst.o2switch.site\\\/rcdd\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/RCDD-9.png\",\"contentUrl\":\"https:\\\/\\\/www.anouk.louisst.o2switch.site\\\/rcdd\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/RCDD-9.png\",\"width\":500,\"height\":300,\"caption\":\"adoligez\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.anouk.louisst.o2switch.site\\\/rcdd\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/RCDD-9.png\"},\"sameAs\":[\"https:\\\/\\\/www.anouk.louisst.o2switch.site\\\/rcdd\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wordpress - Relation Client \u00e0 Distance et Digitalisation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wordpress\/","og_locale":"fr_FR","og_type":"article","og_title":"Wordpress - Relation Client \u00e0 Distance et Digitalisation","og_description":"WORDPRESS A sa cr\u00e9ation en 2003, WordPress \u00e9tait un logiciel permettant le blogging. Mais rapidement, Matt Mullenweg, fondateur de WordPress l\u2019a fait \u00e9voluer vers un r\u00e9el CMS (Content Management System). Aujourd\u2019hui WordPress est devenu un outil incontournable pour la r\u00e9alisation de sites internet. Ainsi, ce sont, en 2022, 43 % des sites qui utilisent WordPress dans le monde, et 20% utilisent WooCommerce ! WordPress est donc d\u00e9sormais un outil qui favorise la relation client \u00e0 distance, et donc la digitalisation de la relation client.\u00a0 Dans le cadre du bloc 2 du BTS NDRC, vous aurez \u00e0 travailler sur la cr\u00e9ation et la personnalisation d\u2019un site WordPress d\u00e9velopp\u00e9 avec le th\u00e8me ASTRA. En effet, le r\u00e9f\u00e9rentiel de BTS NDRC implique l&rsquo;acquisition de 31 comp\u00e9tences pour valider l&rsquo;examen. \u00a0 Tutoriels vid\u00e9o WordPress Comp\u00e9tences de l&rsquo;examen Les r\u00f4les dans WordPress Tous Apparence Astra Contenu Menu SEO Utilisateurs SEO YOAST SEO Menu Int\u00e9grer les cat\u00e9gories au menu Apparence Les menus Contenu Les commentaires Apparence Les blocs WordPress Contenu Cat\u00e9gories et \u00e9tiquettes Apparence Ins\u00e9rer une galerie d&#8217;images Contenu Liens internes et externes 1 2 Apparence Cr\u00e9er ou modifier l&#8217;identit\u00e9 du site (slogan, ic\u00f4ne, logo) Modifier l&#8217;en-t\u00eate (texte, photo, vid\u00e9o) Activer les r\u00e9seaux sociaux (menu r\u00e9seaux sociaux et widget &#8220;ic\u00f4ne des r\u00e9seaux sociaux&#8221;) Utiliser une biblioth\u00e8que m\u00e9dia Ajuster, et positionner un m\u00e9dia Renseigner les textes alternatifs, le titre, la l\u00e9gende et la description de l&rsquo;image \u00a0 Contenu Cr\u00e9er, modifier, publier et supprimer un article, une page et une cat\u00e9gorie R\u00e9diger de mani\u00e8re professionnelle (orthographe, syntaxe, prise en compte du contexte commercial) Utiliser les blocs : titre, paragraphe, bouton, banni\u00e8re, image, galerie, tableau, flux RSS, calendrier, audio, fichier Ajouter un m\u00e9dia (photo, vid\u00e9o, audio) Cr\u00e9er et ins\u00e9rer des liens internes et externes Ins\u00e9rer une carte dynamique via le bloc Map Epingler un article Mod\u00e9rer et r\u00e9pondre \u00e0 un commentaire G\u00e9n\u00e9rer et compl\u00e9ter une page de politique de confidentialit\u00e9 Menu Cr\u00e9er ou modifier les menus et sous-menus Ajouter \u00e0 un menu (cat\u00e9gorie, page, lien personnalis\u00e9) Param\u00e9trer le menu des r\u00e9seaux sociaux Navigation Utiliser les onglets backoffice et frontoffice Param\u00e9trer la page d&rsquo;accueil (page statique ou affichage des derniers articles) Modifier les r\u00e9glages de lecture et de commentaires R\u00e9f\u00e9rencement naturel (SEO) Structurer le texte (titre, sous-titres) Utiliser des mots cl\u00e9s Utiliser des liens internes et externes Renseigner les \u00e9tiquettes, balises et descriptions Activer et utiliser l&rsquo;extension Yoast SEO (requ\u00eate cible, meta\u00a0description Utilisateurs Cr\u00e9er, modifier ou supprimer un compte Attribuer un r\u00f4le Changer l&rsquo;auteur d&rsquo;un article ou d&rsquo;une page WordPress offre la possibilit\u00e9 de d\u00e9finir diff\u00e9rents r\u00f4les pour les utilisateurs. En effet, plusieurs utilisateurs participent souvent \u00e0 la cr\u00e9ation et \u00e0 la maintenance du site. Dans cet article, nous allons voir quels sont les r\u00f4les disponibles dans WordPress, quelles sont leurs caract\u00e9ristiques et comment les attribuer aux utilisateurs. Les r\u00f4les dans WordPress sont un moyen efficace de g\u00e9rer les droits et les responsabilit\u00e9s des utilisateurs. Il est important de choisir le r\u00f4le appropri\u00e9 pour chaque utilisateur en fonction de ses besoins et de ses comp\u00e9tences. Cela permet de garantir la s\u00e9curit\u00e9, la qualit\u00e9 et la coh\u00e9rence du contenu du site. WordPress propose six r\u00f4les par d\u00e9faut pour les utilisateurs : administrateur, \u00e9diteur, auteur, contributeur, abonn\u00e9 super-administrateur (ce dernier n\u2019appara\u00eet que dans les sites \u00ab\u00a0multisites\u2019). Il est possible de modifier ou de cr\u00e9er des r\u00f4les personnalis\u00e9s avec des extensions sp\u00e9cifiques. Pour attribuer un r\u00f4le \u00e0 un utilisateur visionnez la vid\u00e9os que vous trouverez dans les\u00a0tutoriels vid\u00e9o\u00a0d\u00e9di\u00e9s \u00e0 WordPress. Chaque r\u00f4le dispose de certaines capacit\u00e9s qui lui permettent d\u2019effectuer des actions sur le site. Vous trouverez dans le tableau ci-dessous les permissions attach\u00e9es \u00e0 chaque r\u00f4le. \u00a0 Abonn\u00e9 Contributeur Auteur Editeur Administrateur R\u00e9daction article NON OUI OUI OUI OUI R\u00e9daction page NON NON NON OUI OUI Insertion d&rsquo;image \u00e0 partir d&rsquo;une URL OUI OUI OUI OUI OUI Acc\u00e8s m\u00e9diath\u00e8que NON OUI OUI OUI OUI Cr\u00e9ation de cat\u00e9gories NON NON OUI OUI OUI Cr\u00e9ation d&rsquo;\u00e9tiquette NON OUI OUI OUI OUI Publier NON OUI OUI OUI OUI Modification de contenu NON NON OUI OUI OUI Suppression OUI OUI Publications personnelles Toutes Toutes Mod\u00e9ration commentaires NON NON NON OUI OUI Consultation profil OUI OUI OUI OUI OUI Yoast SEO OUI OUI OUI OUI OUI Gestion des options du site NON NON NON NON OUI Utiliser une biblioth\u00e8que m\u00e9dia Ajuster, et positionner un m\u00e9dia Renseigner les textes alternatifs, le titre, la l\u00e9gende et la description de l&rsquo;image \u00a0 Contenu Cr\u00e9er, modifier, publier et supprimer un article, une page et une cat\u00e9gorie R\u00e9diger de mani\u00e8re professionnelle (orthographe, syntaxe, prise en compte du contexte commercial) Utiliser les blocs : titre, paragraphe, bouton, banni\u00e8re, image, galerie, tableau, flux RSS, calendrier, audio, fichier Ajouter un m\u00e9dia (photo, vid\u00e9o, audio) Cr\u00e9er et ins\u00e9rer des liens internes et externes Ins\u00e9rer une carte dynamique via le bloc Map Epingler un article Mod\u00e9rer et r\u00e9pondre \u00e0 un commentaire G\u00e9n\u00e9rer et compl\u00e9ter une page de politique de confidentialit\u00e9 Menu Cr\u00e9er ou modifier les menus et sous-menus Ajouter \u00e0 un menu (cat\u00e9gorie, page, lien personnalis\u00e9) Param\u00e9trer le menu des r\u00e9seaux sociaux Navigation Utiliser les onglets backoffice et frontoffice Param\u00e9trer la page d&rsquo;accueil (page statique ou affichage des derniers articles) Modifier les r\u00e9glages de lecture et de commentaires R\u00e9f\u00e9rencement naturel (SEO) Structurer le texte (titre, sous-titres) Utiliser des mots cl\u00e9s Utiliser des liens internes et externes Renseigner les \u00e9tiquettes, balises et descriptions Activer et utiliser l&rsquo;extension Yoast SEO (requ\u00eate cible, meta\u00a0description Utilisateurs Cr\u00e9er, modifier ou supprimer un compte Attribuer un r\u00f4le Changer l&rsquo;auteur d&rsquo;un article ou d&rsquo;une page WordPress offre la possibilit\u00e9 de d\u00e9finir diff\u00e9rents r\u00f4les pour les utilisateurs. En effet, plusieurs utilisateurs participent souvent \u00e0 la cr\u00e9ation et \u00e0 la maintenance du site. Dans cet article, nous allons voir quels sont les r\u00f4les disponibles dans WordPress, quelles sont leurs caract\u00e9ristiques et comment les attribuer aux utilisateurs. Les r\u00f4les dans WordPress sont un moyen efficace de g\u00e9rer les droits et les responsabilit\u00e9s des utilisateurs. Il est important de choisir le r\u00f4le appropri\u00e9 pour chaque utilisateur en fonction de ses besoins et de ses comp\u00e9tences. Cela permet de garantir la s\u00e9curit\u00e9, la qualit\u00e9 et la coh\u00e9rence du","og_url":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wordpress\/","og_site_name":"Relation Client \u00e0 Distance et Digitalisation","article_modified_time":"2023-12-04T09:32:48+00:00","og_image":[{"url":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/plugins\/visual-portfolio\/assets\/images\/logo-dark.svg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wordpress\/","url":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wordpress\/","name":"Wordpress - Relation Client \u00e0 Distance et Digitalisation","isPartOf":{"@id":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wordpress\/#primaryimage"},"image":{"@id":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wordpress\/#primaryimage"},"thumbnailUrl":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/plugins\/visual-portfolio\/assets\/images\/logo-dark.svg","datePublished":"2023-11-19T09:23:29+00:00","dateModified":"2023-12-04T09:32:48+00:00","breadcrumb":{"@id":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wordpress\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wordpress\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wordpress\/#primaryimage","url":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/plugins\/visual-portfolio\/assets\/images\/logo-dark.svg","contentUrl":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/plugins\/visual-portfolio\/assets\/images\/logo-dark.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wordpress\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/"},{"@type":"ListItem","position":2,"name":"WordPress"}]},{"@type":"WebSite","@id":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/#website","url":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/","name":"Relation Client \u00e0 Distance et Digitalisation","description":"BTS NDRC","publisher":{"@id":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/#\/schema\/person\/f30535236471ed9f12122e0e70841b24"},"alternateName":"RCDD","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/#\/schema\/person\/f30535236471ed9f12122e0e70841b24","name":"adoligez","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/03\/RCDD-9.png","url":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/03\/RCDD-9.png","contentUrl":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/03\/RCDD-9.png","width":500,"height":300,"caption":"adoligez"},"logo":{"@id":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-content\/uploads\/2023\/03\/RCDD-9.png"},"sameAs":["https:\/\/www.anouk.louisst.o2switch.site\/rcdd"]}]}},"_links":{"self":[{"href":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-json\/wp\/v2\/pages\/4434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-json\/wp\/v2\/comments?post=4434"}],"version-history":[{"count":143,"href":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-json\/wp\/v2\/pages\/4434\/revisions"}],"predecessor-version":[{"id":5393,"href":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-json\/wp\/v2\/pages\/4434\/revisions\/5393"}],"wp:attachment":[{"href":"https:\/\/www.anouk.louisst.o2switch.site\/rcdd\/wp-json\/wp\/v2\/media?parent=4434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}